{"id":92704,"date":"2026-03-11T11:07:06","date_gmt":"2026-03-11T10:07:06","guid":{"rendered":"https:\/\/www.domusacademy.com\/?p=92704"},"modified":"2026-03-11T11:07:06","modified_gmt":"2026-03-11T10:07:06","slug":"domus-academy-lanza-nuevos-talleres-con-empresas-lideres-en-marzo-2026","status":"publish","type":"post","link":"https:\/\/www.domusacademy.com\/es\/news\/domus-academy-lanza-nuevos-talleres-con-empresas-lideres-en-marzo-2026\/","title":{"rendered":"Domus Academy lanza nuevos talleres con empresas l\u00edderes en marzo"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":13,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-92704","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Domus Academy lanza nuevos talleres con empresas l\u00edderes en marzo - Domus Academy<\/title>\n<meta name=\"description\" content=\"ESSILORLUXOTTICA, Accurat y Olivetti Historical Archives Association: estas son solo algunas de las empresas que colaboran en nuestros nuevos talleres de marzo. \u00a1Desc\u00fabrelas todas!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.domusacademy.com\/es\/news\/domus-academy-lanza-nuevos-talleres-con-empresas-lideres-en-marzo-2026\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Domus Academy lanza nuevos talleres con empresas l\u00edderes en marzo - Domus Academy\" \/>\n<meta property=\"og:description\" content=\"ESSILORLUXOTTICA, Accurat y Olivetti Historical Archives Association: estas son solo algunas de las empresas que colaboran en nuestros nuevos talleres de marzo. \u00a1Desc\u00fabrelas todas!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.domusacademy.com\/es\/news\/domus-academy-lanza-nuevos-talleres-con-empresas-lideres-en-marzo-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Domus Academy\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-11T10:07:06+00:00\" \/>\n<meta name=\"author\" content=\"Luca Gruttadauria\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Luca Gruttadauria\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.domusacademy.com\/es\/news\/domus-academy-lanza-nuevos-talleres-con-empresas-lideres-en-marzo-2026\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.domusacademy.com\/es\/news\/domus-academy-lanza-nuevos-talleres-con-empresas-lideres-en-marzo-2026\/\"},\"author\":{\"@type\":\"Organization\",\"name\":\"Domus Academy\",\"url\":\"https:\/\/www.domusacademy.com\/es\/\"},\"headline\":\"Domus Academy lanza nuevos talleres con empresas l\u00edderes en marzo\",\"datePublished\":\"2026-03-11T10:07:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.domusacademy.com\/es\/news\/domus-academy-lanza-nuevos-talleres-con-empresas-lideres-en-marzo-2026\/\"},\"wordCount\":11,\"publisher\":{\"@id\":\"https:\/\/www.domusacademy.com\/es\/#organization\"},\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-ES\",\"image\":[\"https:\/\/www.domusacademy.com\/wp-content\/uploads\/2026\/02\/640.360-8.jpg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.domusacademy.com\/es\/news\/domus-academy-lanza-nuevos-talleres-con-empresas-lideres-en-marzo-2026\/\",\"url\":\"https:\/\/www.domusacademy.com\/es\/news\/domus-academy-lanza-nuevos-talleres-con-empresas-lideres-en-marzo-2026\/\",\"name\":\"Domus Academy lanza nuevos talleres con empresas l\u00edderes en marzo - Domus Academy\",\"isPartOf\":{\"@id\":\"https:\/\/www.domusacademy.com\/es\/#website\"},\"datePublished\":\"2026-03-11T10:07:06+00:00\",\"description\":\"ESSILORLUXOTTICA, Accurat y Olivetti Historical Archives Association: estas son solo algunas de las empresas que colaboran en nuestros nuevos talleres de marzo. \u00a1Desc\u00fabrelas todas!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.domusacademy.com\/es\/news\/domus-academy-lanza-nuevos-talleres-con-empresas-lideres-en-marzo-2026\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.domusacademy.com\/es\/news\/domus-academy-lanza-nuevos-talleres-con-empresas-lideres-en-marzo-2026\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.domusacademy.com\/es\/news\/domus-academy-lanza-nuevos-talleres-con-empresas-lideres-en-marzo-2026\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.domusacademy.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Domus Academy lanza nuevos talleres con empresas l\u00edderes en marzo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.domusacademy.com\/es\/#website\",\"url\":\"https:\/\/www.domusacademy.com\/es\/\",\"name\":\"Domus Academy\",\"description\":\"Escuela de Moda y Dise\u00f1o de Mil\u00e1n\",\"publisher\":{\"@id\":\"https:\/\/www.domusacademy.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.domusacademy.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.domusacademy.com\/es\/#organization\",\"name\":\"Domus Academy\",\"url\":\"https:\/\/www.domusacademy.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.domusacademy.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.domusacademy.com\/wp-content\/uploads\/2021\/10\/da-logo-img.png\",\"contentUrl\":\"https:\/\/www.domusacademy.com\/wp-content\/uploads\/2021\/10\/da-logo-img.png\",\"width\":250,\"height\":250,\"caption\":\"Domus Academy\"},\"image\":{\"@id\":\"https:\/\/www.domusacademy.com\/es\/#\/schema\/logo\/image\/\"},\"email\":\"info@domusacademy.it\",\"telephone\":\"+39-02-479-24471\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Domus Academy lanza nuevos talleres con empresas l\u00edderes en marzo - Domus Academy","description":"ESSILORLUXOTTICA, Accurat y Olivetti Historical Archives Association: estas son solo algunas de las empresas que colaboran en nuestros nuevos talleres de marzo. \u00a1Desc\u00fabrelas todas!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.domusacademy.com\/es\/news\/domus-academy-lanza-nuevos-talleres-con-empresas-lideres-en-marzo-2026\/","og_locale":"es_ES","og_type":"article","og_title":"Domus Academy lanza nuevos talleres con empresas l\u00edderes en marzo - Domus Academy","og_description":"ESSILORLUXOTTICA, Accurat y Olivetti Historical Archives Association: estas son solo algunas de las empresas que colaboran en nuestros nuevos talleres de marzo. \u00a1Desc\u00fabrelas todas!","og_url":"https:\/\/www.domusacademy.com\/es\/news\/domus-academy-lanza-nuevos-talleres-con-empresas-lideres-en-marzo-2026\/","og_site_name":"Domus Academy","article_published_time":"2026-03-11T10:07:06+00:00","author":"Luca Gruttadauria","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Luca Gruttadauria"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.domusacademy.com\/es\/news\/domus-academy-lanza-nuevos-talleres-con-empresas-lideres-en-marzo-2026\/#article","isPartOf":{"@id":"https:\/\/www.domusacademy.com\/es\/news\/domus-academy-lanza-nuevos-talleres-con-empresas-lideres-en-marzo-2026\/"},"author":{"@type":"Organization","name":"Domus Academy","url":"https:\/\/www.domusacademy.com\/es\/"},"headline":"Domus Academy lanza nuevos talleres con empresas l\u00edderes en marzo","datePublished":"2026-03-11T10:07:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.domusacademy.com\/es\/news\/domus-academy-lanza-nuevos-talleres-con-empresas-lideres-en-marzo-2026\/"},"wordCount":11,"publisher":{"@id":"https:\/\/www.domusacademy.com\/es\/#organization"},"articleSection":["Noticias"],"inLanguage":"es-ES","image":["https:\/\/www.domusacademy.com\/wp-content\/uploads\/2026\/02\/640.360-8.jpg"]},{"@type":"WebPage","@id":"https:\/\/www.domusacademy.com\/es\/news\/domus-academy-lanza-nuevos-talleres-con-empresas-lideres-en-marzo-2026\/","url":"https:\/\/www.domusacademy.com\/es\/news\/domus-academy-lanza-nuevos-talleres-con-empresas-lideres-en-marzo-2026\/","name":"Domus Academy lanza nuevos talleres con empresas l\u00edderes en marzo - Domus Academy","isPartOf":{"@id":"https:\/\/www.domusacademy.com\/es\/#website"},"datePublished":"2026-03-11T10:07:06+00:00","description":"ESSILORLUXOTTICA, Accurat y Olivetti Historical Archives Association: estas son solo algunas de las empresas que colaboran en nuestros nuevos talleres de marzo. \u00a1Desc\u00fabrelas todas!","breadcrumb":{"@id":"https:\/\/www.domusacademy.com\/es\/news\/domus-academy-lanza-nuevos-talleres-con-empresas-lideres-en-marzo-2026\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.domusacademy.com\/es\/news\/domus-academy-lanza-nuevos-talleres-con-empresas-lideres-en-marzo-2026\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.domusacademy.com\/es\/news\/domus-academy-lanza-nuevos-talleres-con-empresas-lideres-en-marzo-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.domusacademy.com\/es\/"},{"@type":"ListItem","position":2,"name":"Domus Academy lanza nuevos talleres con empresas l\u00edderes en marzo"}]},{"@type":"WebSite","@id":"https:\/\/www.domusacademy.com\/es\/#website","url":"https:\/\/www.domusacademy.com\/es\/","name":"Domus Academy","description":"Escuela de Moda y Dise\u00f1o de Mil\u00e1n","publisher":{"@id":"https:\/\/www.domusacademy.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.domusacademy.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.domusacademy.com\/es\/#organization","name":"Domus Academy","url":"https:\/\/www.domusacademy.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.domusacademy.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.domusacademy.com\/wp-content\/uploads\/2021\/10\/da-logo-img.png","contentUrl":"https:\/\/www.domusacademy.com\/wp-content\/uploads\/2021\/10\/da-logo-img.png","width":250,"height":250,"caption":"Domus Academy"},"image":{"@id":"https:\/\/www.domusacademy.com\/es\/#\/schema\/logo\/image\/"},"email":"info@domusacademy.it","telephone":"+39-02-479-24471"}]}},"_links":{"self":[{"href":"https:\/\/www.domusacademy.com\/es\/wp-json\/wp\/v2\/posts\/92704","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.domusacademy.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.domusacademy.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.domusacademy.com\/es\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.domusacademy.com\/es\/wp-json\/wp\/v2\/comments?post=92704"}],"version-history":[{"count":0,"href":"https:\/\/www.domusacademy.com\/es\/wp-json\/wp\/v2\/posts\/92704\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.domusacademy.com\/es\/wp-json\/wp\/v2\/media?parent=92704"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.domusacademy.com\/es\/wp-json\/wp\/v2\/categories?post=92704"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.domusacademy.com\/es\/wp-json\/wp\/v2\/tags?post=92704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}