{"id":92644,"date":"2026-03-09T17:39:00","date_gmt":"2026-03-09T16:39:00","guid":{"rendered":"https:\/\/www.domusacademy.com\/?p=92644"},"modified":"2026-04-24T11:30:51","modified_gmt":"2026-04-24T09:30:51","slug":"talleres-y-visitas-al-campus-milan-design-week","status":"publish","type":"post","link":"https:\/\/www.domusacademy.com\/es\/news\/talleres-y-visitas-al-campus-milan-design-week\/","title":{"rendered":"Talleres y Visitas al Campus | Milan Design Week"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[70],"tags":[],"class_list":["post-92644","post","type-post","status-publish","format-standard","hentry","category-eventos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Talleres y Visitas al Campus | Milan Design Week - Domus Academy<\/title>\n<meta name=\"description\" content=\"Durante la Milan Design Week 2026, \u00fanete a Domus Academy para vivir una inspiradora semana de visitas personalizadas al campus y talleres creativos. \u00a1Reg\u00edstrate ahora!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.domusacademy.com\/es\/news\/talleres-y-visitas-al-campus-milan-design-week\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Talleres y Visitas al Campus | Milan Design Week - Domus Academy\" \/>\n<meta property=\"og:description\" content=\"Durante la Milan Design Week 2026, \u00fanete a Domus Academy para vivir una inspiradora semana de visitas personalizadas al campus y talleres creativos. \u00a1Reg\u00edstrate ahora!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.domusacademy.com\/es\/news\/talleres-y-visitas-al-campus-milan-design-week\/\" \/>\n<meta property=\"og:site_name\" content=\"Domus Academy\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-09T16:39:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-24T09:30:51+00:00\" \/>\n<meta name=\"author\" content=\"Silvia Ceriani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Silvia Ceriani\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.domusacademy.com\/es\/news\/talleres-y-visitas-al-campus-milan-design-week\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.domusacademy.com\/es\/news\/talleres-y-visitas-al-campus-milan-design-week\/\"},\"author\":{\"@type\":\"Organization\",\"name\":\"Domus Academy\",\"url\":\"https:\/\/www.domusacademy.com\/es\/\"},\"headline\":\"Talleres y Visitas al Campus | Milan Design Week\",\"datePublished\":\"2026-03-09T16:39:00+00:00\",\"dateModified\":\"2026-04-24T09:30:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.domusacademy.com\/es\/news\/talleres-y-visitas-al-campus-milan-design-week\/\"},\"wordCount\":8,\"publisher\":{\"@id\":\"https:\/\/www.domusacademy.com\/es\/#organization\"},\"articleSection\":[\"Eventos\"],\"inLanguage\":\"es-ES\",\"image\":[\"https:\/\/www.domusacademy.com\/wp-content\/uploads\/2026\/02\/Flyers-from-the-future.jpg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.domusacademy.com\/es\/news\/talleres-y-visitas-al-campus-milan-design-week\/\",\"url\":\"https:\/\/www.domusacademy.com\/es\/news\/talleres-y-visitas-al-campus-milan-design-week\/\",\"name\":\"Talleres y Visitas al Campus | Milan Design Week - Domus Academy\",\"isPartOf\":{\"@id\":\"https:\/\/www.domusacademy.com\/es\/#website\"},\"datePublished\":\"2026-03-09T16:39:00+00:00\",\"dateModified\":\"2026-04-24T09:30:51+00:00\",\"description\":\"Durante la Milan Design Week 2026, \u00fanete a Domus Academy para vivir una inspiradora semana de visitas personalizadas al campus y talleres creativos. \u00a1Reg\u00edstrate ahora!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.domusacademy.com\/es\/news\/talleres-y-visitas-al-campus-milan-design-week\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.domusacademy.com\/es\/news\/talleres-y-visitas-al-campus-milan-design-week\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.domusacademy.com\/es\/news\/talleres-y-visitas-al-campus-milan-design-week\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.domusacademy.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Talleres y Visitas al Campus | Milan Design Week\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.domusacademy.com\/es\/#website\",\"url\":\"https:\/\/www.domusacademy.com\/es\/\",\"name\":\"Domus Academy\",\"description\":\"Scuola di Moda e Design Milano\",\"publisher\":{\"@id\":\"https:\/\/www.domusacademy.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.domusacademy.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.domusacademy.com\/es\/#organization\",\"name\":\"Domus Academy\",\"url\":\"https:\/\/www.domusacademy.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.domusacademy.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.domusacademy.com\/wp-content\/uploads\/2021\/10\/da-logo-img.png\",\"contentUrl\":\"https:\/\/www.domusacademy.com\/wp-content\/uploads\/2021\/10\/da-logo-img.png\",\"width\":250,\"height\":250,\"caption\":\"Domus Academy\"},\"image\":{\"@id\":\"https:\/\/www.domusacademy.com\/es\/#\/schema\/logo\/image\/\"},\"email\":\"info@domusacademy.it\",\"telephone\":\"+39-02-479-24471\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Talleres y Visitas al Campus | Milan Design Week - Domus Academy","description":"Durante la Milan Design Week 2026, \u00fanete a Domus Academy para vivir una inspiradora semana de visitas personalizadas al campus y talleres creativos. \u00a1Reg\u00edstrate ahora!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.domusacademy.com\/es\/news\/talleres-y-visitas-al-campus-milan-design-week\/","og_locale":"es_ES","og_type":"article","og_title":"Talleres y Visitas al Campus | Milan Design Week - Domus Academy","og_description":"Durante la Milan Design Week 2026, \u00fanete a Domus Academy para vivir una inspiradora semana de visitas personalizadas al campus y talleres creativos. \u00a1Reg\u00edstrate ahora!","og_url":"https:\/\/www.domusacademy.com\/es\/news\/talleres-y-visitas-al-campus-milan-design-week\/","og_site_name":"Domus Academy","article_published_time":"2026-03-09T16:39:00+00:00","article_modified_time":"2026-04-24T09:30:51+00:00","author":"Silvia Ceriani","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Silvia Ceriani"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.domusacademy.com\/es\/news\/talleres-y-visitas-al-campus-milan-design-week\/#article","isPartOf":{"@id":"https:\/\/www.domusacademy.com\/es\/news\/talleres-y-visitas-al-campus-milan-design-week\/"},"author":{"@type":"Organization","name":"Domus Academy","url":"https:\/\/www.domusacademy.com\/es\/"},"headline":"Talleres y Visitas al Campus | Milan Design Week","datePublished":"2026-03-09T16:39:00+00:00","dateModified":"2026-04-24T09:30:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.domusacademy.com\/es\/news\/talleres-y-visitas-al-campus-milan-design-week\/"},"wordCount":8,"publisher":{"@id":"https:\/\/www.domusacademy.com\/es\/#organization"},"articleSection":["Eventos"],"inLanguage":"es-ES","image":["https:\/\/www.domusacademy.com\/wp-content\/uploads\/2026\/02\/Flyers-from-the-future.jpg"]},{"@type":"WebPage","@id":"https:\/\/www.domusacademy.com\/es\/news\/talleres-y-visitas-al-campus-milan-design-week\/","url":"https:\/\/www.domusacademy.com\/es\/news\/talleres-y-visitas-al-campus-milan-design-week\/","name":"Talleres y Visitas al Campus | Milan Design Week - Domus Academy","isPartOf":{"@id":"https:\/\/www.domusacademy.com\/es\/#website"},"datePublished":"2026-03-09T16:39:00+00:00","dateModified":"2026-04-24T09:30:51+00:00","description":"Durante la Milan Design Week 2026, \u00fanete a Domus Academy para vivir una inspiradora semana de visitas personalizadas al campus y talleres creativos. \u00a1Reg\u00edstrate ahora!","breadcrumb":{"@id":"https:\/\/www.domusacademy.com\/es\/news\/talleres-y-visitas-al-campus-milan-design-week\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.domusacademy.com\/es\/news\/talleres-y-visitas-al-campus-milan-design-week\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.domusacademy.com\/es\/news\/talleres-y-visitas-al-campus-milan-design-week\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.domusacademy.com\/es\/"},{"@type":"ListItem","position":2,"name":"Talleres y Visitas al Campus | Milan Design Week"}]},{"@type":"WebSite","@id":"https:\/\/www.domusacademy.com\/es\/#website","url":"https:\/\/www.domusacademy.com\/es\/","name":"Domus Academy","description":"Scuola di Moda e Design Milano","publisher":{"@id":"https:\/\/www.domusacademy.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.domusacademy.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.domusacademy.com\/es\/#organization","name":"Domus Academy","url":"https:\/\/www.domusacademy.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.domusacademy.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.domusacademy.com\/wp-content\/uploads\/2021\/10\/da-logo-img.png","contentUrl":"https:\/\/www.domusacademy.com\/wp-content\/uploads\/2021\/10\/da-logo-img.png","width":250,"height":250,"caption":"Domus Academy"},"image":{"@id":"https:\/\/www.domusacademy.com\/es\/#\/schema\/logo\/image\/"},"email":"info@domusacademy.it","telephone":"+39-02-479-24471"}]}},"_links":{"self":[{"href":"https:\/\/www.domusacademy.com\/es\/wp-json\/wp\/v2\/posts\/92644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.domusacademy.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.domusacademy.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.domusacademy.com\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.domusacademy.com\/es\/wp-json\/wp\/v2\/comments?post=92644"}],"version-history":[{"count":0,"href":"https:\/\/www.domusacademy.com\/es\/wp-json\/wp\/v2\/posts\/92644\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.domusacademy.com\/es\/wp-json\/wp\/v2\/media?parent=92644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.domusacademy.com\/es\/wp-json\/wp\/v2\/categories?post=92644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.domusacademy.com\/es\/wp-json\/wp\/v2\/tags?post=92644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}